{"id":340,"date":"2016-11-09T11:54:02","date_gmt":"2016-11-09T09:54:02","guid":{"rendered":"https:\/\/staratnight.de\/blog\/?p=340"},"modified":"2018-12-02T16:14:56","modified_gmt":"2018-12-02T14:14:56","slug":"fuer-windows-ungueltige-dateinamen-auf-einem-usb-stick-reparieren","status":"publish","type":"post","link":"https:\/\/staratnight.de\/blog\/fuer-windows-ungueltige-dateinamen-auf-einem-usb-stick-reparieren\/","title":{"rendered":"F\u00fcr Windows ung\u00fcltige Dateinamen auf einem USB-Stick reparieren"},"content":{"rendered":"<p>Ich habe letzte Woche einen USB-Stick mit TV-Aufnahmen erhalten.\u00a0 Leider konnte mein Fernseher zwar die Ordner anzeigen, die Dateien darin aber nicht einlesen und hat sie immer als &#8222;leer&#8220; dargestellt.<\/p>\n<p>Unter Windows habe ich mir den Inhalt des Sticks dann mal angeschaut und folgenden Aufbau der darauf enthaltenen Dateien und Ordner gefunden:<\/p>\n<blockquote><p><em><strong>Name der Sendung:Inhalt der Folge<\/strong><\/em><\/p><\/blockquote>\n<p>Mit dem &#8222;:&#8220; im Namen kann Windows nichts anfangen. Was nun? Umbenennen funktioniert nicht, weder \u00fcber den Windows Explorer, noch \u00fcber die Kommandozeile. Kopieren geht nat\u00fcrlich auch nicht&#8230;nach ein wenig googeln und einigen Fehlversuchen kam&#8230;<\/p>\n<p><!--more--><\/p>\n<h1>CHKDSK der Weltenretter<\/h1>\n<p><strong><em>Achtung:<\/em> Bei dem Vorgehen werden einige Informationen verlorengehen! Lest den Artikel erst bis zum Ende und entscheidet erst anschlie\u00dfend, ob ihr diesen Weg wirklich gehen m\u00f6chtet. <\/strong><\/p>\n<p>Wie bin ich dabei vorgegangen?<\/p>\n<ul>\n<li>Eingabeaufforderung <strong>als Administrator<\/strong> \u00f6ffnen<\/li>\n<li>auf das Laufwerk unter dem der USB-Stick gemappt wurde wechseln<\/li>\n<li>folgenden Aufruf ausf\u00fchren<br \/>\n<blockquote><p>chkdsk \/V \/F<\/p><\/blockquote>\n<\/li>\n<li>Daraufhin l\u00e4uft CHKDSK los und \u00fcberpr\u00fcft den USB-Stick<br \/>\n<strong>Wichtig:<\/strong> Der Stick darf dabei durch keinen anderen Prozess blockiert sein. Alle anderen Zugriffe (also etwa durch offene Windows-Explorer-Fenster). Dies kann durch die zus\u00e4tzliche Angabe \/X erzwungen werden<\/p>\n<ul>\n<li>Der Stick selbst &#8211; der ansonsten hoffentlich in Ordnung ist &#8211; \u00fcbersteht die Pr\u00fcfung. Die Ordner und Dateien mit dem &#8222;falschen&#8220; Namen aber werden als falsch indiziert erkannt und durch CHKDSK &#8222;repariert&#8220;.<\/li>\n<li>Das hei\u00dft nicht anderes, als das Windows die Ordner und Dateien in einen versteckten Systemordner mit dem Namen found.000 verschiebt (die Nummer kann abweichen).<\/li>\n<\/ul>\n<\/li>\n<li>Um an diesen Ordner nun heranzukommen, werden alle seine Attribute zur\u00fcckgesetzt<br \/>\n<blockquote><p>attrib -S -H -R -A<\/p><\/blockquote>\n<\/li>\n<li>Der Zugriff wird aber weiterhin verweigert. Um diesen wiederzubekommen, den Windows Explorer aufrufen und auf das Laufwerk des USB-Sticks wechseln.<br \/>\n<strong>Hinweis:<\/strong> Sollte dies fehlen, den Stick einfach nochmal neu einstecken.<\/p>\n<ul>\n<li>\u00dcber das Kontextmen\u00fc die Eigenschaften aufrufen\n<ul>\n<li>Hierf\u00fcr sind Administrationsrechte erforderlich. Je nachdem, wie euer Windows konfiguriert ist, m\u00fcsst ihr euch hier also als Admin authentifizieren.<\/li>\n<\/ul>\n<\/li>\n<li>Im Eigenschaftendialog auf den Reiter <em>Sicherheit<\/em> wechseln und auf <em>Bearbeiten <\/em>klicken.\n<ul>\n<li>Hier nun <em>Hinzuf\u00fcgen<\/em> anklicken, in das Eingabefeld <em>Jeder<\/em> eintragen und mit <em>OK <\/em>best\u00e4tigen.<br \/>\n<em>Jeder <\/em>steht nun in der Liste der <em>Gruppen- oder Benutzernamen<\/em><\/li>\n<li>Diesen neuen Eintrag markieren und in der unteren Liste bei <em>Vollzugriff <\/em>den Haken bei <em>Zulassen <\/em>machen<\/li>\n<li>Alle Eigenschaftendialoge mit <em>OK <\/em>best\u00e4tigen<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h1>Keine perfekte L\u00f6sung<\/h1>\n<p>Das war&#8217;s. Wir haben die Dateien nun wieder zugreifbar und k\u00f6nnen damit arbeiten. Einziger Wehrmutstropfen: die Dateinamen sind vollst\u00e4ndig verloren gegangen und einfach nur mit CHK0000.chk durchnummeriert. Hier ist also noch ein wenig Nacharbeit erforderlich.<\/p>\n<p>Bei zu vielen Dateien solltet ihr also dann doch besser auf eine Linux-Notfall-CD zur\u00fcckgreifen, wie etwa<\/p>\n<ul>\n<li>Trinity Rescue Kit &#8211; <a href=\"http:\/\/trinityhome.org\/\">http:\/\/trinityhome.org\/<\/a><\/li>\n<li>SystemRescueCd &#8211; <a href=\"http:\/\/www.system-rescue-cd.org\/Online-Manual-DE\">https:\/\/www.system-rescue-cd.org<\/a> (mit deutscher Beschreibung)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ich habe letzte Woche einen USB-Stick mit TV-Aufnahmen erhalten.\u00a0 Leider konnte mein Fernseher zwar die Ordner anzeigen, die Dateien darin aber nicht einlesen&hellip;<\/p>\n","protected":false},"author":1,"featured_media":429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-windows"],"_links":{"self":[{"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/posts\/340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/comments?post=340"}],"version-history":[{"count":2,"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/posts\/340\/revisions"}],"predecessor-version":[{"id":348,"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/posts\/340\/revisions\/348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/media\/429"}],"wp:attachment":[{"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/media?parent=340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/categories?post=340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staratnight.de\/blog\/wp-json\/wp\/v2\/tags?post=340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}